{"id":14534,"date":"2024-09-12T09:20:28","date_gmt":"2024-09-12T14:20:28","guid":{"rendered":"https:\/\/satrack.com\/co\/?page_id=14534"},"modified":"2025-11-24T14:53:38","modified_gmt":"2025-11-24T19:53:38","slug":"ultima-milla-old","status":"publish","type":"page","link":"https:\/\/satrack.com\/co\/ultima-milla-old\/","title":{"rendered":"\u00daltima Milla"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"14534\" class=\"elementor elementor-14534\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-33b6e6c e-flex e-con-boxed e-con e-parent\" data-id=\"33b6e6c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f6d2194 e-con-full e-flex e-con e-child\" data-id=\"f6d2194\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-48b1b51 elementor-widget elementor-widget-heading\" data-id=\"48b1b51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Controla tus operaciones de \u00faltima milla<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23346d3 elementor-widget elementor-widget-text-editor\" data-id=\"23346d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Con Satrack \u00daltima Milla podras gestionar las entregas, visitas y recogidas con informaci\u00f3n detallada y al instante<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aede8e6 e-flex e-con-boxed e-con e-child\" data-id=\"aede8e6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9b44589 elementor-widget elementor-widget-button\" data-id=\"9b44589\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contacto\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-user-check\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 256c70.7 0 128-57.3 128-128S294.7 0 224 0 96 57.3 96 128s57.3 128 128 128zm89.6 32h-16.7c-22.2 10.2-46.9 16-72.9 16s-50.6-5.8-72.9-16h-16.7C60.2 288 0 348.2 0 422.4V464c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48v-41.6c0-74.2-60.2-134.4-134.4-134.4zm323-128.4l-27.8-28.1c-4.6-4.7-12.1-4.7-16.8-.1l-104.8 104-45.5-45.8c-4.6-4.7-12.1-4.7-16.8-.1l-28.1 27.9c-4.7 4.6-4.7 12.1-.1 16.8l81.7 82.3c4.6 4.7 12.1 4.7 16.8.1l141.3-140.2c4.6-4.7 4.7-12.2.1-16.8z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Asesoria personalizada<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2e320a1 e-con-full e-flex e-con e-child\" data-id=\"2e320a1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-badd012 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"badd012\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomInRight&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"924\" height=\"684\" src=\"https:\/\/satrack.com\/co\/wp-content\/uploads\/sites\/2\/2022\/12\/ultima_milla_full.png\" class=\"attachment-full size-full wp-image-14686\" alt=\"hombre repartiendo una caja\" title=\"ultima_milla_full\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-191d984 e-flex e-con-boxed e-con e-parent\" data-id=\"191d984\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b2502b elementor-widget elementor-widget-shortcode\" data-id=\"5b2502b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"breadcrumbs\"><a href=\"https:\/\/satrack.com\/co\">Inicio<\/a><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0c4838b e-flex e-con-boxed e-con e-parent\" data-id=\"0c4838b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7d40c4b elementor-widget elementor-widget-heading\" data-id=\"7d40c4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfQu\u00e9 es la log\u00edstica de \u00faltima milla?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18361c9 elementor-widget elementor-widget-text-editor\" data-id=\"18361c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>La log\u00edstica de \u00faltima milla es esencial en la entrega de productos y su eficiencia puede mejorar la reputaci\u00f3n de una empresa. El rastreo satelital, basado en la tecnolog\u00eda GPS, es fundamental para anticipar el tiempo de entrega y mejorar la comunicaci\u00f3n con el cliente.<\/p><p>El servicio de \u00faltima milla se enfoca en la entrega de productos en general y en cualquier entrega a un domicilio particular. La log\u00edstica de \u00faltima milla es una parte importante del servicio de entrega a domicilio y para garantizar la satisfacci\u00f3n del cliente.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0d2f3b5 e-flex e-con-boxed e-con e-parent\" data-id=\"0d2f3b5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f30017f e-con-full e-flex e-con e-child\" data-id=\"f30017f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4bf7f93 elementor-widget elementor-widget-heading\" data-id=\"4bf7f93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Realiz\u00e1 un <strong>seguimiento en tiempo real<\/strong>\ncon nuestro servicio de \u00faltima milla\ny optimiz\u00e1 tus entregas.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f373453 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"f373453\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Con el servicio de \u00faltima milla, sabr\u00e1s si tus\nveh\u00edculos:<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b09d9e elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4b09d9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00bfSe est\u00e1n cumpliendo con los tiempos pactados? <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00bfTus clientes est\u00e1n recibiendo sus entregas?<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00bfSabes el estado de los env\u00edos?<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u00bfLas rutas de entrega est\u00e1n optimizadas?<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0546e81 e-con-full e-flex e-con e-child\" data-id=\"0546e81\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0998ac0 animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"0998ac0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1081\" height=\"680\" src=\"https:\/\/satrack.com\/co\/wp-content\/uploads\/sites\/2\/2022\/12\/img_entregas.png\" class=\"attachment-full size-full wp-image-14661\" alt=\"infografia en notebook\" title=\"img_entregas\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-14d97a1 e-flex e-con-boxed e-con e-parent\" data-id=\"14d97a1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5cc5c4b e-con-full e-flex e-con e-child\" data-id=\"5cc5c4b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cc52450 animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"cc52450\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/satrack.com\/co\/wp-content\/uploads\/sites\/2\/2022\/12\/Diseno-sin-titulo-20-pxjahc3vdnreuo78094s5e2vm4rc7cdd5gun4n1ysw.png\" class=\"attachment-full size-full wp-image-14720\" alt=\"infografia en pc\" title=\"Diseno-sin-titulo-20-pxjahc3vdnreuo78094s5e2vm4rc7cdd5gun4n1ysw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dbeca29 e-con-full e-flex e-con e-child\" data-id=\"dbeca29\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8dc4913 elementor-widget elementor-widget-heading\" data-id=\"8dc4913\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CONTROL TRACKER<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c394979 elementor-widget elementor-widget-heading\" data-id=\"c394979\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Planifica tus rutas de reparto f\u00e1cilmente<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41dbd7a elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"41dbd7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Aumenta la eficiencia en el reparto y ten control de las rutas con nuestro sistema de seguimiento satelital<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ab0421 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9ab0421\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Delimitaci\u00f3n de zonas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Optimizador de rutas de acuerdo a tiempo, distancia y trafico<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-13138b8 e-flex e-con-boxed e-con e-parent\" data-id=\"13138b8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;curve&quot;,&quot;shape_divider_bottom_negative&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M500,97C126.7,96.3,0.8,19.8,0,0v100l1000,0V1C1000,19.4,873.3,97.8,500,97z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-279e7c6 e-con-full e-flex e-con e-child\" data-id=\"279e7c6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ebd601b elementor-widget elementor-widget-heading\" data-id=\"ebd601b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SMART NOTIFICATION<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4416c11 elementor-widget elementor-widget-heading\" data-id=\"4416c11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lleva el control de tus entregas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-993d2e6 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"993d2e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Controla las entregas efectivas de tus rutas y manten los registros y soportes que le dan confiabilidad a tus clientes.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f601f45 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f601f45\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Soportes de entrega a trav\u00e9s de registro fotografico y firma digital<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Recibe alertas y novedades en ruta<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Notifica a tus clientes<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b84179a e-con-full e-flex e-con e-child\" data-id=\"b84179a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a59959d animated-slow elementor-invisible elementor-widget elementor-widget-image\" data-id=\"a59959d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/satrack.com\/co\/wp-content\/uploads\/sites\/2\/2022\/12\/Diseno-sin-titulo-23.png\" class=\"attachment-full size-full wp-image-14725\" alt=\"infografia en pc\" title=\"Diseno-sin-titulo-23\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ca94f6e e-flex e-con-boxed e-con e-parent\" data-id=\"ca94f6e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4ca338f e-flex e-con-boxed e-con e-child\" data-id=\"4ca338f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-085de65 e-con-full e-flex e-con e-child\" data-id=\"085de65\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-591e323 elementor-view-framed elementor-widget__width-inherit elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"591e323\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Capa_1\" data-name=\"Capa 1\" viewBox=\"0 0 512 512\"><path d=\"M256.69,312.35a5,5,0,0,1-5-5,73.6,73.6,0,0,0-15.34-45.21,5,5,0,0,1,7.93-6.09,83.47,83.47,0,0,1,17.41,51.3A5,5,0,0,1,256.69,312.35Z\"><\/path><path d=\"M98.11,312.35a5,5,0,0,1-5-5,84.34,84.34,0,0,1,113.71-79,5,5,0,0,1-3.49,9.37,74.34,74.34,0,0,0-100.22,69.64A5,5,0,0,1,98.11,312.35Z\"><\/path><path d=\"M177.4,421.88H154a5,5,0,1,1,0-10H177.4a74.47,74.47,0,0,0,60.74-31.5,5,5,0,1,1,8.17,5.76A84.45,84.45,0,0,1,177.4,421.88Z\"><\/path><path d=\"M111.16,387.88H88.52c-9.4,0-17-8.08-17-18V321.71c0-9.93,7.64-18,17-18h10.1a5,5,0,0,1,4.29,2.43l14.19,23.74h0a33.94,33.94,0,0,1,4.78,17.46v29.38A11,11,0,0,1,111.16,387.88ZM88.52,313.7c-3.88,0-7,3.59-7,8v48.17c0,4.41,3.16,8,7,8h22.64c.29,0,.72-.47.72-1.17V347.33A24,24,0,0,0,108.52,335L95.78,313.7Z\"><\/path><path d=\"M266.28,387.88H243.64a11,11,0,0,1-10.72-11.17V347.33a34,34,0,0,1,4.78-17.46h0l14.19-23.74a5,5,0,0,1,4.29-2.43h10.1c9.4,0,17,8.08,17,18v48.17C283.32,379.8,275.68,387.88,266.28,387.88Zm-20-52.88h0a24,24,0,0,0-3.36,12.33v29.38c0,.7.43,1.17.72,1.17h22.64c3.88,0,7-3.59,7-8V321.71c0-4.42-3.16-8-7-8H259Z\"><\/path><path d=\"M132.5,267.45a5,5,0,0,1-3.54-8.54,68.61,68.61,0,0,1,74.29-15,5,5,0,0,1-3.78,9.26A58.61,58.61,0,0,0,136,266,5,5,0,0,1,132.5,267.45Z\"><\/path><path d=\"M222.3,267.45a5,5,0,0,1-3.53-1.47,61.93,61.93,0,0,0-4.75-4.26,5,5,0,1,1,6.26-7.79,70.82,70.82,0,0,1,5.56,5,5,5,0,0,1-3.54,8.54Z\"><\/path><rect x=\"144.94\" y=\"409.43\" width=\"26.54\" height=\"14.9\" rx=\"7.45\"><\/rect><path d=\"M298,258.6a87.49,87.49,0,0,1-47.2-13.72l-22.75,6.72a10,10,0,0,1-12.62-12l6.1-25.47A88,88,0,1,1,298,258.6Zm-46.39-24.17a5.07,5.07,0,0,1,2.8.86,77.94,77.94,0,1,0-23.26-24.51,5.07,5.07,0,0,1,.58,3.75L225.18,242l25-7.31A4.93,4.93,0,0,1,251.64,234.43Z\"><\/path><path d=\"M307,223H289.11a2.5,2.5,0,0,1-2.5-2.5v-6.12a44.22,44.22,0,0,1-11.44-4.75L270.84,214a2.57,2.57,0,0,1-3.54,0l-12.61-12.61a2.5,2.5,0,0,1,0-3.54l4.33-4.33a44.63,44.63,0,0,1-4.75-11.44h-6.12a2.49,2.49,0,0,1-2.5-2.5V161.72a2.49,2.49,0,0,1,2.5-2.5h6.12A44.63,44.63,0,0,1,259,147.78l-4.33-4.34a2.49,2.49,0,0,1,0-3.53L267.3,127.3a2.5,2.5,0,0,1,3.54,0l4.33,4.32a44.54,44.54,0,0,1,11.44-4.74v-6.12a2.5,2.5,0,0,1,2.5-2.5H307a2.5,2.5,0,0,1,2.5,2.5v6.12a44.84,44.84,0,0,1,11.44,4.74l4.33-4.32a2.49,2.49,0,0,1,3.53,0l12.62,12.61a2.5,2.5,0,0,1,0,3.53L337,147.78a45,45,0,0,1,4.74,11.44h6.12a2.49,2.49,0,0,1,2.5,2.5v17.83a2.49,2.49,0,0,1-2.5,2.5h-6.12A45,45,0,0,1,337,193.49l4.33,4.33a2.51,2.51,0,0,1,0,3.54L328.75,214a2.5,2.5,0,0,1-1.77.74h0a2.47,2.47,0,0,1-1.76-.74l-4.33-4.33a44.51,44.51,0,0,1-11.44,4.75v6.12A2.5,2.5,0,0,1,307,223Zm-15.34-5h12.84v-5.6a2.48,2.48,0,0,1,2-2.44,39.86,39.86,0,0,0,13.46-5.59,2.51,2.51,0,0,1,3.13.33l4,4,9.08-9.08-4-4a2.51,2.51,0,0,1-.33-3.13A40.06,40.06,0,0,0,337.36,179a2.49,2.49,0,0,1,2.44-2h5.6V164.22h-5.6a2.49,2.49,0,0,1-2.44-2,40.06,40.06,0,0,0-5.59-13.47,2.51,2.51,0,0,1,.33-3.13l4-4L327,132.6l-4,4a2.51,2.51,0,0,1-3.13.33,39.86,39.86,0,0,0-13.46-5.59,2.48,2.48,0,0,1-2-2.44v-5.6H291.61v5.6a2.49,2.49,0,0,1-2,2.44,39.82,39.82,0,0,0-13.47,5.59,2.51,2.51,0,0,1-3.13-.33l-4-4L260,141.68l4,4a2.5,2.5,0,0,1,.33,3.13,40.06,40.06,0,0,0-5.59,13.47,2.49,2.49,0,0,1-2.44,2h-5.6v12.83h5.6a2.49,2.49,0,0,1,2.44,2,40.06,40.06,0,0,0,5.59,13.47,2.5,2.5,0,0,1-.33,3.13l-4,4,9.08,9.08,4-4a2.5,2.5,0,0,1,3.13-.33A39.82,39.82,0,0,0,289.63,210a2.49,2.49,0,0,1,2,2.44Z\"><\/path><path d=\"M364.63,315.2a76.11,76.11,0,0,1-74.35-60.64,5,5,0,1,1,9.8-2A65.91,65.91,0,0,0,401.47,294a5,5,0,0,1,4.21-.65l20.21,6L420.54,277a5.07,5.07,0,0,1,.58-3.75,65.9,65.9,0,0,0-41.27-98,5,5,0,0,1,2.29-9.74,75.93,75.93,0,0,1,48.6,111.15l5.15,21.48a9.32,9.32,0,0,1-11.7,11.11l-19.12-5.65A75.57,75.57,0,0,1,364.63,315.2Z\"><\/path><path d=\"M298,197.06a26.43,26.43,0,1,1,26.42-26.43A26.46,26.46,0,0,1,298,197.06Zm0-47.85a21.43,21.43,0,1,0,21.42,21.42A21.45,21.45,0,0,0,298,149.21Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tTu servicio al cliente ser\u00e1 un tema sencillo al tener todas las respuestas a un clic y con soportes.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-54ce3c0 e-con-full e-flex e-con e-child\" data-id=\"54ce3c0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0a09b20 elementor-view-framed elementor-widget__width-inherit elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"0a09b20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Capa_1\" data-name=\"Capa 1\" viewBox=\"0 0 512 512\"><path d=\"M235.25,384.63A28.62,28.62,0,1,1,263.86,356,28.65,28.65,0,0,1,235.25,384.63Zm0-47.23A18.62,18.62,0,1,0,253.86,356,18.63,18.63,0,0,0,235.25,337.4Z\"><\/path><path d=\"M379.44,384.63A28.62,28.62,0,1,1,408.05,356,28.65,28.65,0,0,1,379.44,384.63Zm0-47.23A18.62,18.62,0,1,0,398.05,356,18.63,18.63,0,0,0,379.44,337.4Z\"><\/path><path d=\"M197.92,339.21H160.63a5,5,0,0,1,0-10h37.29a5,5,0,1,1,0,10Z\"><\/path><path d=\"M422.17,357.27H402.78a5,5,0,0,1,0-10h14.39V305.94c-.86-3.12-6.28-20.28-20.42-20.28a5,5,0,0,1,0-10c23.46,0,30,27.36,30.3,28.52a5.33,5.33,0,0,1,.12,1.12v47A5,5,0,0,1,422.17,357.27Z\"><\/path><path d=\"M356.12,357.27H258.57a5,5,0,1,1,0-10h97.55a5,5,0,0,1,0,10Z\"><\/path><path d=\"M211.93,357.27H185.6A11.34,11.34,0,0,1,174.27,346V335a5,5,0,0,1,10,0v11a1.33,1.33,0,0,0,1.33,1.32h26.33a5,5,0,1,1,0,10Z\"><\/path><path d=\"M397.27,297.92H352.11a5,5,0,0,1-5-5V238.85a5,5,0,0,1,5-5h34.62a12.67,12.67,0,0,1,12.62,11.87l2.91,46.89a5,5,0,0,1-5,5.31Zm-40.16-10H392l-2.58-41.58a2.66,2.66,0,0,0-2.64-2.49H357.11Z\"><\/path><path d=\"M352.11,308.37a5,5,0,0,1-5-5V230.08a3.26,3.26,0,0,0-3.25-3.26H285.24a5,5,0,0,1,0-10h58.62a13.27,13.27,0,0,1,13.25,13.26v73.29A5,5,0,0,1,352.11,308.37Z\"><\/path><path d=\"M352.11,357.27a5,5,0,0,1-5-5V317.82a5,5,0,0,1,10,0v34.45A5,5,0,0,1,352.11,357.27Z\"><\/path><path d=\"M179.27,316.27a94.45,94.45,0,1,1,94.45-94.45,93.48,93.48,0,0,1-20.39,58.63,5,5,0,0,1-7.84-6.21,83.57,83.57,0,0,0,18.23-52.42,84.43,84.43,0,1,0-31.24,65.59,5,5,0,0,1,6.3,7.76A94.62,94.62,0,0,1,179.27,316.27Z\"><\/path><path d=\"M179.27,158.33a2.49,2.49,0,0,1-2.5-2.5V145.1a2.5,2.5,0,0,1,5,0v10.73A2.49,2.49,0,0,1,179.27,158.33Z\"><\/path><path d=\"M179.27,301.05a2.5,2.5,0,0,1-2.5-2.5V287.81a2.5,2.5,0,0,1,5,0v10.74A2.49,2.49,0,0,1,179.27,301.05Z\"><\/path><path d=\"M146.28,167.17a2.47,2.47,0,0,1-2.16-1.25l-5.37-9.3a2.5,2.5,0,0,1,4.33-2.5l5.37,9.3a2.5,2.5,0,0,1-.92,3.42A2.44,2.44,0,0,1,146.28,167.17Z\"><\/path><path d=\"M217.64,290.77a2.51,2.51,0,0,1-2.17-1.25l-5.37-9.3a2.5,2.5,0,1,1,4.33-2.5l5.37,9.3a2.5,2.5,0,0,1-2.16,3.75Z\"><\/path><path d=\"M122.13,191.33a2.45,2.45,0,0,1-1.25-.34l-9.3-5.37a2.5,2.5,0,1,1,2.5-4.33l9.3,5.37a2.5,2.5,0,0,1-1.25,4.67Z\"><\/path><path d=\"M245.72,262.68a2.44,2.44,0,0,1-1.25-.33l-9.3-5.37a2.5,2.5,0,0,1,2.5-4.33L247,258a2.5,2.5,0,0,1-1.25,4.66Z\"><\/path><path d=\"M113.29,224.32H102.55a2.5,2.5,0,0,1,0-5h10.74a2.5,2.5,0,1,1,0,5Z\"><\/path><path d=\"M256,224.32H245.26a2.5,2.5,0,0,1,0-5H256a2.5,2.5,0,0,1,0,5Z\"><\/path><path d=\"M112.83,262.68a2.5,2.5,0,0,1-1.25-4.66l9.3-5.37a2.5,2.5,0,0,1,2.5,4.33l-9.3,5.37A2.49,2.49,0,0,1,112.83,262.68Z\"><\/path><path d=\"M236.42,191.33a2.5,2.5,0,0,1-1.25-4.67l9.3-5.37a2.5,2.5,0,1,1,2.5,4.33l-9.3,5.37A2.45,2.45,0,0,1,236.42,191.33Z\"><\/path><path d=\"M140.91,290.77a2.45,2.45,0,0,1-1.25-.34,2.5,2.5,0,0,1-.91-3.41l5.37-9.3a2.5,2.5,0,1,1,4.33,2.5l-5.37,9.3A2.52,2.52,0,0,1,140.91,290.77Z\"><\/path><path d=\"M212.27,167.17a2.44,2.44,0,0,1-1.25-.33,2.5,2.5,0,0,1-.92-3.42l5.37-9.3a2.5,2.5,0,0,1,4.33,2.5l-5.37,9.3A2.47,2.47,0,0,1,212.27,167.17Z\"><\/path><path d=\"M179.27,226.82a5,5,0,0,1-5-5V188.05a5,5,0,0,1,10,0v33.77A5,5,0,0,1,179.27,226.82Z\"><\/path><path d=\"M223.79,226.82H179.27a5,5,0,0,1,0-10h44.52a5,5,0,1,1,0,10Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tDisminuye tus tiempos de distribuci\u00f3n y alin\u00e9ate con los tiempos de tu cliente.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7953b44 e-con-full e-flex e-con e-child\" data-id=\"7953b44\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-400f9a6 elementor-view-framed elementor-widget__width-inherit elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"400f9a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Capa_1\" data-name=\"Capa 1\" viewBox=\"0 0 512 512\"><path d=\"M326,181.92h-.21a5,5,0,0,1-3.9-2.15l-11.43-16.55a5,5,0,1,1,8.22-5.69l7.67,11.1,23.83-29a5,5,0,1,1,7.73,6.35l-28,34.12A5,5,0,0,1,326,181.92Z\"><\/path><path d=\"M386.42,221.13h-89a5,5,0,1,1,0-10h89a5,5,0,0,1,0,10Z\"><\/path><circle cx=\"270.59\" cy=\"214.77\" r=\"6.08\"><\/circle><path d=\"M386.42,242.55h-89a5,5,0,0,1,0-10h89a5,5,0,0,1,0,10Z\"><\/path><circle cx=\"270.59\" cy=\"236.2\" r=\"6.08\"><\/circle><path d=\"M386.42,264h-89a5,5,0,0,1,0-10h89a5,5,0,0,1,0,10Z\"><\/path><circle cx=\"270.59\" cy=\"257.62\" r=\"6.08\"><\/circle><path d=\"M386.42,285.4h-89a5,5,0,1,1,0-10h89a5,5,0,0,1,0,10Z\"><\/path><circle cx=\"270.59\" cy=\"279.04\" r=\"6.08\"><\/circle><path d=\"M386.42,306.82H313.19a5,5,0,0,1,0-10h73.23a5,5,0,0,1,0,10Z\"><\/path><path d=\"M407.75,329.59h-91.5a5,5,0,0,1,0-10h86.5V122.12H257.86v79.55a5,5,0,0,1-10,0V117.12a5,5,0,0,1,5-5H407.75a5,5,0,0,1,5,5V324.59A5,5,0,0,1,407.75,329.59Z\"><\/path><path d=\"M412.83,348.91H316.25a5,5,0,0,1,0-10h96.58a8.32,8.32,0,0,0,8.31-8.31V111.11a8.32,8.32,0,0,0-8.31-8.31h-165a8.32,8.32,0,0,0-8.31,8.31v78a5,5,0,0,1-10,0v-78A18.33,18.33,0,0,1,247.78,92.8h165a18.33,18.33,0,0,1,18.31,18.31V330.6A18.33,18.33,0,0,1,412.83,348.91Z\"><\/path><path d=\"M195.85,414.2h-105a5,5,0,0,1-5-5V318a5,5,0,0,1,5-5h105a5,5,0,0,1,5,5v91.2A5,5,0,0,1,195.85,414.2Zm-100-10h95V323h-95Z\"><\/path><path d=\"M130.94,359.39a2.56,2.56,0,0,1-1.17-.29,2.51,2.51,0,0,1-1.33-2.21V318a2.5,2.5,0,0,1,2.5-2.5h24.84a2.49,2.49,0,0,1,2.5,2.5v38.89a2.49,2.49,0,0,1-3.9,2.07l-11-7.46-11,7.46A2.57,2.57,0,0,1,130.94,359.39Zm2.5-38.89v31.68l8.52-5.77a2.49,2.49,0,0,1,2.81,0l8.51,5.77V320.5Z\"><\/path><path d=\"M90.85,323a5,5,0,0,1-4.17-7.75l14.85-22.62a5,5,0,0,1,4.18-2.26h37.66a5,5,0,0,1,0,10h-35L95,320.74A5,5,0,0,1,90.85,323Z\"><\/path><path d=\"M131,320.5a2.94,2.94,0,0,1-.51-.05,2.5,2.5,0,0,1-1.94-3l4.69-22.63a2.5,2.5,0,1,1,4.9,1l-4.7,22.63A2.49,2.49,0,0,1,131,320.5Z\"><\/path><path d=\"M300.83,414.2h-105a5,5,0,0,1-5-5V318a5,5,0,0,1,5-5h105a5,5,0,0,1,5,5v91.2A5,5,0,0,1,300.83,414.2Zm-100-10h95V323h-95Z\"><\/path><path d=\"M260.75,359.39a2.53,2.53,0,0,1-1.4-.43l-11-7.46-11,7.46a2.5,2.5,0,0,1-3.9-2.07V318a2.5,2.5,0,0,1,2.5-2.5h24.84a2.5,2.5,0,0,1,2.5,2.5v38.89a2.51,2.51,0,0,1-1.33,2.21A2.56,2.56,0,0,1,260.75,359.39ZM248.33,346a2.46,2.46,0,0,1,1.4.43l8.52,5.77V320.5H238.41v31.68l8.52-5.77A2.46,2.46,0,0,1,248.33,346Z\"><\/path><path d=\"M300.84,323a5,5,0,0,1-4.19-2.26l-13.37-20.37H248.33a5,5,0,0,1,0-10H286a5,5,0,0,1,4.18,2.26L305,315.25a5,5,0,0,1-4.17,7.75Z\"><\/path><path d=\"M260.75,320.5a2.51,2.51,0,0,1-2.45-2l-4.69-22.63a2.5,2.5,0,1,1,4.89-1l4.7,22.63a2.51,2.51,0,0,1-1.94,3A3,3,0,0,1,260.75,320.5Z\"><\/path><path d=\"M248.34,323h-105a5,5,0,0,1-5-5V226.8a5,5,0,0,1,5-5h105a5,5,0,0,1,5,5V318A5,5,0,0,1,248.34,323Zm-100-10h95V231.8h-95Z\"><\/path><path d=\"M208.26,268.19a2.57,2.57,0,0,1-1.41-.43l-11-7.47-11,7.47a2.52,2.52,0,0,1-2.58.13,2.49,2.49,0,0,1-1.33-2.2V226.8a2.49,2.49,0,0,1,2.5-2.5h24.85a2.49,2.49,0,0,1,2.5,2.5v38.89a2.5,2.5,0,0,1-1.33,2.2A2.45,2.45,0,0,1,208.26,268.19Zm-12.43-13.42a2.59,2.59,0,0,1,1.41.43l8.52,5.77V229.3H185.91V261l8.52-5.77A2.58,2.58,0,0,1,195.83,254.77Z\"><\/path><path d=\"M248.34,231.8a5,5,0,0,1-4.18-2.26l-13.37-20.37H160.9l-13.37,20.37a5,5,0,1,1-8.36-5.49L154,201.43a5,5,0,0,1,4.17-2.26h75.29a5,5,0,0,1,4.18,2.26l14.85,22.62a5,5,0,0,1-4.18,7.75Z\"><\/path><path d=\"M208.25,229.3a2.5,2.5,0,0,1-2.44-2l-4.7-22.62a2.5,2.5,0,0,1,4.9-1l4.69,22.63a2.49,2.49,0,0,1-1.94,3A2.22,2.22,0,0,1,208.25,229.3Z\"><\/path><path d=\"M183.42,229.3a2.22,2.22,0,0,1-.51-.06,2.49,2.49,0,0,1-1.94-3l4.69-22.63a2.5,2.5,0,1,1,4.9,1l-4.7,22.62A2.5,2.5,0,0,1,183.42,229.3Z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tMant\u00e9n tu cliente informado sobre el estado de sus entregas e informes detallados de la operaci\u00f3n.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5020195 e-flex e-con-boxed e-con e-parent\" data-id=\"5020195\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-521b9b6 elementor-widget elementor-widget-video\" data-id=\"521b9b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/2DEHpGr1ScM&quot;,&quot;lazy_load&quot;:&quot;yes&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f79cdf e-flex e-con-boxed e-con e-parent\" data-id=\"3f79cdf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-71174d0 elementor-testimonial--align-left elementor-testimonial--skin-default elementor-testimonial--layout-image_inline elementor-pagination-type-bullets elementor-widget elementor-widget-testimonial-carousel\" data-id=\"71174d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_per_view&quot;:&quot;3&quot;,&quot;slides_per_view_tablet&quot;:&quot;2&quot;,&quot;slides_to_scroll&quot;:&quot;3&quot;,&quot;slides_to_scroll_tablet&quot;:&quot;2&quot;,&quot;speed&quot;:1200,&quot;autoplay_speed&quot;:8000,&quot;lazyload&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:42,&quot;sizes&quot;:[]},&quot;pagination&quot;:&quot;bullets&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"testimonial-carousel.default\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>\u201cUtilizando Gesti\u00f3n de Entregas de Satrack se facilitan los procesos log\u00edsticos de nuestros clientes y les brindamos beneficios adicionales para que no nos vean s\u00f3lo como una transportadora sino como un aliado para hacer m\u00e1s eficiente su gesti\u00f3n de entregas\u201d.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/satrack.com\/co\/wp-content\/uploads\/sites\/2\/2022\/12\/logo_internadinos.jpg\" alt=\"JHOMAR HOLGU\u00cdN\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">JHOMAR HOLGU\u00cdN<\/span><span class=\"elementor-testimonial__title\">Gerente Nacional de Operaciones.<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial__content\">\n\t\t\t\t\t<div class=\"elementor-testimonial__text\">\n\t\t\t\t\t\t<p>\u201cAplicar la tecnolog\u00eda en nuestros procesos nos permite posicionarnos en un mercado emergente y competitivo\u201d<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-testimonial__footer\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial__image\">\n\t\t\t\t\t\t<img class=\"swiper-lazy\" data-src=\"https:\/\/satrack.com\/co\/wp-content\/uploads\/sites\/2\/2022\/12\/logo_milla7.jpg\" alt=\"ALEJANDRO AGUDELO\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<cite class=\"elementor-testimonial__cite\"><span class=\"elementor-testimonial__name\">ALEJANDRO AGUDELO<\/span><span class=\"elementor-testimonial__title\">Director de Inteligencia de Negocio.<\/span><\/cite>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ce70a96 e-flex e-con-boxed e-con e-parent\" data-id=\"ce70a96\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_top&quot;:&quot;curve&quot;,&quot;shape_divider_top_negative&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"true\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 1000 100\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M500,97C126.7,96.3,0.8,19.8,0,0v100l1000,0V1C1000,19.4,873.3,97.8,500,97z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7ac8274 e-con-full e-flex e-con e-child\" data-id=\"7ac8274\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-de0937e e-con-full e-flex e-con e-child\" data-id=\"de0937e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38d5c87 elementor-widget elementor-widget-heading\" data-id=\"38d5c87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Accede a una demo de nuestro producto<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed83ccd elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"ed83ccd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Te mostraremos las funcionalidades y adecuaremos un plan de implementaci\u00f3n con base en las necesidades de tu operaci\u00f3n, tambien podras acceder a todas las carracteristicas y funcionalidades de nuestro sistema.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f79605c e-con-full e-flex e-con e-child\" data-id=\"f79605c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ec5a0b0 e-con-full e-flex e-con e-child\" data-id=\"ec5a0b0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cbaae13 elementor-widget elementor-widget-counter\" data-id=\"cbaae13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">USUARIOS ACTIVOS<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"350\" data-from-value=\"0\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">+<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ade5056 e-con-full e-flex e-con e-child\" data-id=\"ade5056\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-910cb46 elementor-widget elementor-widget-counter\" data-id=\"910cb46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">KILOMETROS RECORRIDOS<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"640\" data-from-value=\"0\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">K+<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-89508c6 e-con-full e-flex e-con e-child\" data-id=\"89508c6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4afc07d elementor-widget elementor-widget-counter\" data-id=\"4afc07d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">MUNICIPIOS TRABAJADOS<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"1103\" data-from-value=\"0\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">+<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-60f6902 e-con-full e-flex e-con e-child\" data-id=\"60f6902\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a827ebe elementor-widget elementor-widget-counter\" data-id=\"a827ebe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">IMPLEMENTACIONES<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"100\" data-from-value=\"0\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">+<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-35f1143 e-flex e-con-boxed e-con e-parent\" data-id=\"35f1143\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ae38ba7 e-con-full e-flex e-con e-child\" data-id=\"ae38ba7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e290071 elementor-widget elementor-widget-heading\" data-id=\"e290071\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Solicita una asesoria ahora<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac49b10 elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"ac49b10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Queremos ayudarte en el proceso de transformaci\u00f3n digital de tu negocio y lograr los mejores resultados en tus operaciones, dejanos ponernos en contacto contigo<\/p>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb3edf4 premium-modal-dismissible-yes elementor-widget elementor-widget-premium-addon-modal-box\" data-id=\"cb3edf4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;premium_modal_box_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"premium-addon-modal-box.default\">\n\t\t\t\t\t\n\t\t<div class=\"premium-modal-box-container\" data-settings=\"{&quot;trigger&quot;:&quot;button&quot;,&quot;show_on_exit&quot;:false}\">\n\t\t\t<div class=\"premium-modal-trigger-container\">\n\t\t\t\t\t\t\t\t\t<button data-toggle=\"premium-modal\" data-target=\"#premium-modal-cb3edf4\" type=\"button\" class=\"premium-modal-trigger-btn premium-btn-lg premium-button-none \" data-text=\"Solicita una asesoria personalizada\">\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"premium-button-text-icon-wrapper\">\n\t\t\t\t\t\t\t<span>Solicita una asesoria personalizada<\/span>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t\t<\/button>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<div id=\"premium-modal-cb3edf4\" class=\"premium-modal-box-modal\"\n\t\t\trole=\"dialog\"\n\t\t\tstyle=\"display: none\"\n\t\t\t>\n\t\t\t\t<div class=\"premium-modal-box-modal-dialog\" data-delay-animation=\"\" data-modal-animation=\"fadeInDown animated-\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-modal-box-modal-header\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"premium-modal-box-close-button-container\">\n\t\t\t\t\t\t\t\t\t<button type=\"button\" class=\"premium-modal-box-modal-close\" data-dismiss=\"premium-modal\">&times;<\/button>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"premium-modal-box-modal-body\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"txt-amarillo\">D\u00e9janos tus datos y te contactaremos lo antes posible.<\/h3>\n<div class=\"copiaform-1\" role=\"main\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-41faecb e-con-full e-flex e-con e-child\" data-id=\"41faecb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ea9cf1 elementor-widget elementor-widget-image\" data-id=\"2ea9cf1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"865\" height=\"508\" src=\"https:\/\/satrack.com\/co\/wp-content\/uploads\/sites\/2\/2022\/12\/manejo_app.png\" class=\"attachment-large size-large wp-image-14747\" alt=\"hombre utilizando celular\" title=\"manejo_app\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ac557ef elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"ac557ef\" data-element_type=\"container\" data-e-type=\"container\" id=\"contacto\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7c64b85 e-con-full e-flex e-con e-child\" data-id=\"7c64b85\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a211874 elementor-widget elementor-widget-heading\" data-id=\"a211874\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00bfte interesa este servicio?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c01c450 elementor-widget elementor-widget-text-editor\" data-id=\"c01c450\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>D\u00e9janos tus datos y te contactaremos lo antes posible.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3d570a elementor-widget elementor-widget-image\" data-id=\"e3d570a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"709\" height=\"426\" src=\"https:\/\/satrack.com\/co\/wp-content\/uploads\/sites\/2\/2022\/12\/img_control_rutas.png\" class=\"attachment-full size-full wp-image-14569\" alt=\"infografias\" title=\"img_control_rutas\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e534a75 e-con-full e-flex e-con e-child\" data-id=\"e534a75\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6b1b077 contenedor-form-pn elementor-widget elementor-widget-shortcode\" data-id=\"6b1b077\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f26303-o1\" lang=\"es-CO\" dir=\"ltr\" data-wpcf7-id=\"26303\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/co\/wp-json\/wp\/v2\/pages\/14534#wpcf7-f26303-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"26303\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_CO\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f26303-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_satrack_ts\" value=\"1784095239\" \/><input type=\"hidden\" name=\"_satrack_sig\" value=\"39a33ac6b50e2329e809b66832292bb8\" \/>\n<\/fieldset>\n<div class=\"formulario-cliente-nuevo\">\n<div id=\"contenedor-botones\">\n        <a class=\"btn btn-light btn-usuario btn-empresa btn-active\">Soy empresa<\/a><a\n            class=\"btn btn-light btn-usuario btn-transportista\">Soy transportista<\/a>\n    <\/div>\n    <div class=\"progress progress-light\">\n        <div class=\"progress-bar progress-bar-striped progress-bar-animated\" role=\"progressbar\" aria-valuenow=\"0\"\n            aria-valuemin=\"0\" aria-valuemax=\"100\" style=\"width: 0%\"><\/div>\n    <\/div>\n\n    <div class=\"contenedor-form-pn secc_nuevo\">\n        <div id=\"cont-secc\">\n            <section class=\"seccion active\" id=\"section_01\">\n                <input class=\"wpcf7-form-control wpcf7-hidden\" id=\"tipo_cliente\" value=\"nuevo\" type=\"hidden\" name=\"tipo_de_persona\" \/>\n                <input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Landing producto \u00daltima Milla\" type=\"hidden\" name=\"origen\" \/>\n                <input class=\"wpcf7-form-control wpcf7-hidden\" value=\"\" type=\"hidden\" name=\"utm_medium\" \/>\n                <div class=\"row-flex my-2\">\n                    <div class=\"col form-outline ctn_required me-1\">\n                        <input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control revision\" id=\"nombre_cliente\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"nombre-cliente\" \/>\n                        <label class=\"form-label\" for=\"nombre_cliente\">Nombres<\/label>\n                    <\/div>\n                <div class=\"col form-outline ctn_required ms-1\">\n                        <input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control revision\" id=\"apellido_cliente\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"apellido_cliente\" \/>\n                        <label class=\"form-label\" for=\"apellido_cliente\">Apellidos<\/label>\n                    <\/div>\n                <\/div>\n                <div class=\"row-flex my-2\">\n                    <div class=\"col form-outline ctn_required\" id=\"cont_empresa\">\n                        <input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text form-control revision\" id=\"empresa\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"empresa\" \/>\n                        <label class=\"form-label lb-required\" for=\"empresa\">Empresa<\/label>\n                    <\/div>\n                <\/div>\n                <div class=\"row-flex my-2\">\n                    <div class=\"form-outline\">\n                        \n    <!-- DEBUG: Pais detectado=col -->\n    <input type='hidden' name='pais' id='pais' value='CO' data-debug-pais='col'>\n\n    <div class='select-page-tel' data-pais-actual='col' data-pais-codigo='CO'>\n      <div class='btn-pais-tel'>\n        <img decoding=\"async\" alt=\"bandera de Colombia\" src=\"https:\/\/satrack.com\/co\/wp-content\/themes\/theme_satrack\/assets\/img\/ban_colombia.svg\" class=\"icono-bandera-tel\" width=\"20\" title=\"\">\n\n        <span class='indicativo'>+57<\/span>\n\n        <div class='icon_flecha'>\n          <svg version='1.1' id='Capa_134' xmlns='http:\/\/www.w3.org\/2000\/svg' viewBox='0 0 512 512'>\n            <path d='M256.7,388.09L12.33,143.72c-3.65-3.65-3.65-9.56,0-13.21c3.65-3.65,9.56-3.65,13.21,0L256.7,361.68l229.76-229.76 c3.65-3.65,9.56-3.65,13.21,0c3.65,3.65,3.65,9.56,0,13.21L256.7,388.09z'><\/path>\n          <\/svg>\n        <\/div>\n      <\/div>\n\n      <ul class='caja-opciones-tel oculto'>\n  \n      <li \n        class='item-pais current-item' \n        valor='CO' \n        indicativo='57' \n        largo='10' \n        data-pais='Colombia'\n      >\n        <img decoding=\"async\" src=\"https:\/\/satrack.com\/co\/wp-content\/themes\/theme_satrack\/assets\/img\/ban_colombia.svg\" class=\"icono-bandera\" width=\"20\" alt=\"bandera de Colombia\" title=\"\">\n        <span class='txt-pais'>Colombia &nbsp;+57<\/span>\n      <\/li>\n    \n      <li \n        class='item-pais current-item' \n        valor='PA' \n        indicativo='507' \n        largo='8' \n        data-pais='Panam\u00e1'\n      >\n        <img decoding=\"async\" src=\"https:\/\/satrack.com\/co\/wp-content\/themes\/theme_satrack\/assets\/img\/ban_panama.svg\" class=\"icono-bandera\" width=\"20\" alt=\"bandera de Panam\u00e1\" title=\"\">\n        <span class='txt-pais'>Panam\u00e1 &nbsp;+507<\/span>\n      <\/li>\n    \n      <li \n        class='item-pais current-item' \n        valor='EC' \n        indicativo='593' \n        largo='9' \n        data-pais='Ecuador'\n      >\n        <img decoding=\"async\" src=\"https:\/\/satrack.com\/co\/wp-content\/themes\/theme_satrack\/assets\/img\/ban_ecuador.svg\" class=\"icono-bandera\" width=\"20\" alt=\"bandera de Ecuador\" title=\"\">\n        <span class='txt-pais'>Ecuador &nbsp;+593<\/span>\n      <\/li>\n    \n      <\/ul>\n    <\/div>\n  \n                    <\/div>\n                    <div class=\"col form-outline ctn_required\">\n                        <input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel form-control revision\" id=\"telefono\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"telefono\" \/>\n                        <label class=\"form-label lb-required\" for=\"telefono\">Tel\u00e9fono<\/label>\n                    <\/div>\n                <\/div>\n                  <div class=\"row-flex my-2\">\n                    <div class=\"col form-outline ctn_required\">\n                        <input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-text wpcf7-validates-as-email form-control revision\" id=\"email_cliente\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"email-cliente\" \/>\n                        <label class=\"form-label lb-required\" for=\"email_cliente\">Correo<\/label>\n                    <\/div>\n                <\/div>\n            <\/section>\n\n            <section class=\"seccion\" id=\"section_02\">\n                <div class=\"row-flex my-2\">\n                    <div class=\"col\">\n                        <label class=\"etiqueta-input lb-required\" for=\"rango_veh\">Tama\u00f1o de tu flota<\/label>\n                        <select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required form-select revision\" id=\"rango_veh\" aria-required=\"true\" aria-invalid=\"false\" name=\"rango_veh\"><option value=\"\">Seleccione una opci\u00f3n...<\/option><option value=\"1 - 4 veh\u00edculos\">1 - 4 veh\u00edculos<\/option><option value=\"5 - 10 veh\u00edculos\">5 - 10 veh\u00edculos<\/option><option value=\"11 - 29 veh\u00edculos\">11 - 29 veh\u00edculos<\/option><option value=\"30 - 50 veh\u00edculos\">30 - 50 veh\u00edculos<\/option><option value=\"51 - 100 veh\u00edculos\">51 - 100 veh\u00edculos<\/option><option value=\"101 - 200 veh\u00edculos\">101 - 200 veh\u00edculos<\/option><option value=\"201-500 veh\u00edculos\">201-500 veh\u00edculos<\/option><option value=\"&gt; 500 veh\u00edculos\">&gt; 500 veh\u00edculos<\/option><\/select>\n                    <\/div>\n                <\/div>\n                <div class=\"row-flex my-2\">\n                    <div class=\"col ctn_required\">\n                        <label class=\"etiqueta-input lb-r\" for=\"tipo-lead\">\u00bfYa conoc\u00edas Satrack?<\/label>\n                        <select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required form-select revision\" id=\"tipo-lead\" aria-required=\"true\" aria-invalid=\"false\" name=\"tipo-lead\"><option value=\"\">&#8212;Por favor, elige una opci\u00f3n&#8212;<\/option><option value=\"Primera vez que tengo contacto\">Primera vez que tengo contacto<\/option><option value=\"Alguna vez cotic\u00e9 sus servicio\">Alguna vez cotic\u00e9 sus servicio<\/option><option value=\"Soy excliente\">Soy excliente<\/option><option value=\"Soy cliente actual\">Soy cliente actual<\/option><\/select>\n                    <\/div>\n                <\/div>\n                <div class=\"row-flex my-2\">\n                    <div class=\"col\" id=\"campo_interes\">\n                        <label class=\"etiqueta-input\" for=\"interes\">\u00bfCu\u00e1l es tu producto de inter\u00e9s?<\/label>\n                        <select class=\"wpcf7-form-control wpcf7-select form-select revision\" id=\"intereses\" aria-invalid=\"false\" name=\"interes\"><option value=\"\">Seleccione un producto<\/option><option value=\"Termocarga\">Termocarga<\/option><option value=\"Telemetr\u00eda \/ Monitoreo\">Telemetr\u00eda \/ Monitoreo<\/option><option value=\"Satrack Conecta\">Satrack Conecta<\/option><option value=\"C\u00e1mara Est\u00e1ndar\">C\u00e1mara Est\u00e1ndar<\/option><option value=\"C\u00e1mara Avanzada\">C\u00e1mara Avanzada<\/option><option value=\"Soluci\u00f3n de combustible\">Soluci\u00f3n de combustible<\/option><\/select>\n                    <\/div>\n                <\/div>\n            <\/section>\n        <\/div>\n    <\/div>\n    <div class=\"row-flex my-2\">\n        <div id=\"contenedor-botones\" class=\"col\">\n            <a class=\"btn btn-line btn-regresar disabled\">Regresar<\/a>\n            <a class=\"btn btn-line btn-siguiente\">Continuar<\/a>\n        <\/div>\n    <\/div>\n    <div class=\"d-flex justify-content-end\"><div class=\"cf7-cf-turnstile\" style=\"margin-top: 0px; margin-bottom: -15px;\"> <div id=\"cf-turnstile-cf7-3225478430\" class=\"cf-turnstile\" data-callback=\"turnstileCF7Callback\" data-sitekey=\"0x4AAAAAACExFoU7beJDiU9o\" data-theme=\"auto\" data-language=\"auto\" data-size=\"compact\" data-retry=\"auto\" data-retry-interval=\"1000\" data-refresh-expired=\"auto\" data-refresh-timeout=\"auto\" data-action=\"contact-form-7\" data-callback=\"turnstileCF7Callback\" data-appearance=\"interaction-only\"><\/div> <style>.wpcf7-submit { pointer-events: none; opacity: 0.5; }<\/style> <script>document.addEventListener(\"DOMContentLoaded\", function() { setTimeout(function(){ var e=document.getElementById(\"cf-turnstile-cf7-3225478430\"); if(e&&!e.innerHTML.trim()){turnstile.render(e, {sitekey:\"0x4AAAAAACExFoU7beJDiU9o\"});} }, 200); });<\/script> <style>#cf-turnstile-cf7-3225478430 iframe { margin-bottom: 15px; }<\/style> <style>#cf-turnstile-cf7-3225478430 { margin-left: -15px; }<\/style> <script>document.addEventListener(\"DOMContentLoaded\",function(){document.querySelectorAll('.wpcf7-form').forEach(function(e){e.addEventListener('submit',function(){if(document.getElementById('cf-turnstile-cf7-3225478430')){setTimeout(function(){turnstile.reset('#cf-turnstile-cf7-3225478430');},1000)}})})});<\/script> <\/div><br\/><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn btn-envio disabled\" id=\"submit\" type=\"submit\" value=\"Solicitar\" \/><\/div>\n<\/div><span class=\"satrack-cf7-hp\" aria-hidden=\"true\"><label>Do not fill this field<input type=\"text\" name=\"_satrack_hp\" value=\"\" tabindex=\"-1\" autocomplete=\"off\"><\/label><\/span><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-56c814b e-flex e-con-boxed e-con e-parent\" data-id=\"56c814b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e8adbff elementor-widget elementor-widget-heading\" data-id=\"e8adbff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ's<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff83aa0 item-faq elementor-widget elementor-widget-eael-adv-accordion\" data-id=\"ff83aa0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-adv-accordion.default\">\n\t\t\t\t\t            <div class=\"eael-adv-accordion\" id=\"eael-adv-accordion-ff83aa0\" data-scroll-on-click=\"no\" data-scroll-speed=\"300\" data-custom-id-offset=\"1\" data-accordion-id=\"ff83aa0\" data-accordion-type=\"accordion\" data-toogle-speed=\"300\">\n            <div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"qu-es-el-servicio-de-ltima-milla\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"0\" data-tab=\"1\" aria-controls=\"elementor-tab-content-2671\"><h3 class=\"eael-accordion-tab-title\">\u00bfQu\u00e9 es el servicio de \u00faltima milla?<\/h3><svg aria-hidden=\"true\" class=\"fa-toggle e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/div><div id=\"elementor-tab-content-2671\" class=\"eael-accordion-content clearfix\" data-tab=\"1\" aria-labelledby=\"qu-es-el-servicio-de-ltima-milla\">El servicio de \u00faltima milla se refiere a la entrega de productos desde un centro de distribuci\u00f3n hasta el destino final, ya sea un domicilio particular o una empresa.<\/div>\n\t\t\t\t\t<\/div><div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"por-qu-es-importante-el-servicio-de-ltima-milla\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"0\" data-tab=\"2\" aria-controls=\"elementor-tab-content-2672\"><h3 class=\"eael-accordion-tab-title\">\u00bfPor qu\u00e9 es importante el servicio de \u00faltima milla?<\/h3><svg aria-hidden=\"true\" class=\"fa-toggle e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/div><div id=\"elementor-tab-content-2672\" class=\"eael-accordion-content clearfix\" data-tab=\"2\" aria-labelledby=\"por-qu-es-importante-el-servicio-de-ltima-milla\"><p>El servicio de \u00faltima milla es importante porque es el momento en que el cliente recibe el producto, y por tanto, su satisfacci\u00f3n depende en gran medida de la eficiencia y rapidez de esta entrega. Un servicio de \u00faltima milla eficiente y bien coordinado puede mejorar la reputaci\u00f3n de una empresa, generar lealtad y fidelizaci\u00f3n de clientes, y aumentar las ventas y beneficios.<\/p><\/div>\n\t\t\t\t\t<\/div><div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"qu-es-el-rastreo-satelital-en-el-servicio-de-ltima-milla\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"0\" data-tab=\"3\" aria-controls=\"elementor-tab-content-2673\"><h3 class=\"eael-accordion-tab-title\">\u00bfQu\u00e9 es el rastreo satelital en el servicio de \u00faltima milla?<\/h3><svg aria-hidden=\"true\" class=\"fa-toggle e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/div><div id=\"elementor-tab-content-2673\" class=\"eael-accordion-content clearfix\" data-tab=\"3\" aria-labelledby=\"qu-es-el-rastreo-satelital-en-el-servicio-de-ltima-milla\">El rastreo satelital es una herramienta que permite conocer en tiempo real la ubicaci\u00f3n del paquete y el tiempo estimado de entrega. Esto ayuda a mejorar la comunicaci\u00f3n con el cliente y a reducir los tiempos de espera, aumentando su satisfacci\u00f3n.<\/div>\n\t\t\t\t\t<\/div><div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"cmo-funciona-el-rastreo-satelital-en-el-servicio-de-ltima-milla\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"0\" data-tab=\"4\" aria-controls=\"elementor-tab-content-2674\"><h3 class=\"eael-accordion-tab-title\">\u00bfC\u00f3mo funciona el rastreo satelital en el servicio de \u00faltima milla?<\/h3><svg aria-hidden=\"true\" class=\"fa-toggle e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/div><div id=\"elementor-tab-content-2674\" class=\"eael-accordion-content clearfix\" data-tab=\"4\" aria-labelledby=\"cmo-funciona-el-rastreo-satelital-en-el-servicio-de-ltima-milla\">El rastreo satelital se basa en la tecnolog\u00eda de GPS, la cual permite conocer en tiempo real la ubicaci\u00f3n del veh\u00edculo que transporta el paquete. Esto se combina con el an\u00e1lisis de datos para prever el tiempo de entrega y mejorar la eficiencia de la log\u00edstica.<\/div>\n\t\t\t\t\t<\/div><div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"qu-es-el-servicio-puerta-a-puerta-en-la-ltima-milla\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"0\" data-tab=\"5\" aria-controls=\"elementor-tab-content-2675\"><h3 class=\"eael-accordion-tab-title\">\u00bfQu\u00e9 es el servicio puerta a puerta en la \u00faltima milla?<\/h3><svg aria-hidden=\"true\" class=\"fa-toggle e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/div><div id=\"elementor-tab-content-2675\" class=\"eael-accordion-content clearfix\" data-tab=\"5\" aria-labelledby=\"qu-es-el-servicio-puerta-a-puerta-en-la-ltima-milla\"><p>El servicio puerta a puerta se refiere a la entrega directa del paquete en la puerta del domicilio del cliente, sin necesidad de que \u00e9ste tenga que desplazarse a alg\u00fan punto de entrega.<\/p><\/div>\n\t\t\t\t\t<\/div><div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"cunto-tiempo-tarda-la-entrega-en-el-servicio-de-ltima-milla\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"0\" data-tab=\"6\" aria-controls=\"elementor-tab-content-2676\"><h3 class=\"eael-accordion-tab-title\">\u00bfCu\u00e1nto tiempo tarda la entrega en el servicio de \u00faltima milla?<\/h3><svg aria-hidden=\"true\" class=\"fa-toggle e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/div><div id=\"elementor-tab-content-2676\" class=\"eael-accordion-content clearfix\" data-tab=\"6\" aria-labelledby=\"cunto-tiempo-tarda-la-entrega-en-el-servicio-de-ltima-milla\"><p>El tiempo de entrega en el servicio de \u00faltima milla puede variar dependiendo de la empresa de entrega y del lugar de destino. Sin embargo, gracias al rastreo satelital, se puede prever el tiempo estimado de entrega y mejorar la eficiencia en la log\u00edstica.<\/p><\/div>\n\t\t\t\t\t<\/div><div class=\"eael-accordion-list\">\n\t\t\t\t\t<div id=\"cmo-puedo-conocer-el-estado-de-mi-envo-en-el-servicio-de-ltima-milla\" class=\"elementor-tab-title eael-accordion-header\" tabindex=\"0\" data-tab=\"7\" aria-controls=\"elementor-tab-content-2677\"><h3 class=\"eael-accordion-tab-title\">\u00bfC\u00f3mo puedo conocer el estado de mi env\u00edo en el servicio de \u00faltima milla?<\/h3><svg aria-hidden=\"true\" class=\"fa-toggle e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><\/div><div id=\"elementor-tab-content-2677\" class=\"eael-accordion-content clearfix\" data-tab=\"7\" aria-labelledby=\"cmo-puedo-conocer-el-estado-de-mi-envo-en-el-servicio-de-ltima-milla\">Puedes conocer el estado de tu env\u00edo a trav\u00e9s del rastreo satelital, el cual te permitir\u00e1 conocer la ubicaci\u00f3n exacta del paquete y el tiempo estimado de entrega. Tambi\u00e9n puedes contactar al servicio al cliente de la empresa de entrega para obtener informaci\u00f3n detallada sobre el estado de tu env\u00edo.<\/div>\n\t\t\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Controla tus operaciones de \u00faltima milla Con Satrack \u00daltima Milla podras gestionar las entregas, visitas y recogidas con informaci\u00f3n detallada y al instante Asesoria personalizada \u00bfQu\u00e9 es la log\u00edstica de \u00faltima milla? La log\u00edstica de \u00faltima milla es esencial en la entrega de productos y su eficiencia puede mejorar la reputaci\u00f3n de una empresa. El [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-14534","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/satrack.com\/co\/wp-json\/wp\/v2\/pages\/14534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/satrack.com\/co\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/satrack.com\/co\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/satrack.com\/co\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/satrack.com\/co\/wp-json\/wp\/v2\/comments?post=14534"}],"version-history":[{"count":0,"href":"https:\/\/satrack.com\/co\/wp-json\/wp\/v2\/pages\/14534\/revisions"}],"wp:attachment":[{"href":"https:\/\/satrack.com\/co\/wp-json\/wp\/v2\/media?parent=14534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}